{"id":7291,"date":"2024-01-06T12:31:59","date_gmt":"2024-01-06T05:31:59","guid":{"rendered":"https:\/\/www.cpiagrotech.com\/?p=7291"},"modified":"2024-06-24T22:23:27","modified_gmt":"2024-06-24T15:23:27","slug":"csr-001","status":"publish","type":"post","link":"https:\/\/www.cpiagrotech.com\/th\/csr-001\/","title":{"rendered":"\"\u0e25\u0e35\u0e25\u0e32\u0e40\u0e01\u0e21\u0e2a\u0e4c\" \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e2a\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2567"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid et_custom_uniqid_new_6671a463a4403 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 et_custom_uniqid_6a56f2cd961ae mpc-column\" data-column-id=\"mpc_column-486a56f2d195c79\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\" style=\"height: 50px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center;\"><strong>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e2a\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2567 \"\u0e25\u0e35\u0e25\u0e32\u0e40\u0e01\u0e21\u0e2a\u0e4c\"<\/strong><\/h1>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4 style=\"text-align: center;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2567 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0a\u0e38\u0e21\u0e1e\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a\u0e25\u0e35\u0e25\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e2a\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2567 \"\u0e25\u0e35\u0e25\u0e32\u0e40\u0e01\u0e21\u0e2a\u0e4c\" \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e13 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e31\u0e19\u0e18\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d.\u0e17\u0e48\u0e32\u0e41\u0e0b\u0e30 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid et_custom_uniqid_6a56f2cd961d4 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_6a56f2cd961ae mpc-column\" data-column-id=\"mpc_column-136a56f2d196b7e\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_left-to-right left-to-right\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-2039745229]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-1024x683.jpeg\" target=\"_self\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-0 (1)\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-0-1.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_6a56f2cd961ae mpc-column\" data-column-id=\"mpc_column-936a56f2d1974b6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_top-to-bottom top-to-bottom\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-954996927]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-1024x683.jpeg\" target=\"_self\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-4\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-4.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_6a56f2cd961ae mpc-column\" data-column-id=\"mpc_column-786a56f2d197da4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_right-to-left right-to-left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-2177999489]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-1024x683.jpeg\" target=\"_self\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-2\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-2.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid et_custom_uniqid_6a56f2cd961d4 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_6a56f2cd961ae mpc-column\" data-column-id=\"mpc_column-956a56f2d198af2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_left-to-right left-to-right\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-2015254734]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-1024x683.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-3\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-3.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_new_667907c039301 mpc-column\" data-column-id=\"mpc_column-656a56f2d199394\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_top-to-bottom top-to-bottom\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-3186972686]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-1024x683.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-5\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-5.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_6a56f2cd961ae mpc-column\" data-column-id=\"mpc_column-276a56f2d199cbf\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_right-to-left right-to-left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-4012136375]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-1024x683.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-6\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-6.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid et_custom_uniqid_6a56f2cd961d4 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_6a56f2cd961ae mpc-column\" data-column-id=\"mpc_column-356a56f2d19aaa9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_left-to-right left-to-right\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-4025508233]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-1024x683.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-8\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-8.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_animate_when_almost_visible wpb_fadeIn fadeIn wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_new_667907c039301 mpc-column\" data-column-id=\"mpc_column-496a56f2d19b382\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_bottom-to-top bottom-to-top\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-3238626515]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-1024x683.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-9\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-9.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_6a56f2cd961ae mpc-column\" data-column-id=\"mpc_column-776a56f2d19bc3f\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center wpb_content_element wpb_animate_when_almost_visible wpb_right-to-left right-to-left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-7291-1693568779]\" href=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-1024x683.jpeg\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-1024x683.jpeg\" class=\"vc_single_image-img attachment-large\" alt=\"\" title=\"gallery-19012024-165010-11\" srcset=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-1024x683.jpeg 1024w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-300x200.jpeg 300w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-768x512.jpeg 768w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-18x12.jpeg 18w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-600x400.jpeg 600w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-1x1.jpeg 1w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11-10x7.jpeg 10w, https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/gallery-19012024-165010-11.jpeg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 6 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2567 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0a\u0e38\u0e21\u0e1e\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2567 \"\u0e25\u0e35\u0e25\u0e32 \u0e40\u0e01\u0e21\u0e2a\u0e4c\" \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u2026<\/p>","protected":false},"author":1,"featured_media":7267,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-7291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-csr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Leela Games&quot; Annual Sports Day 2024 - CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cpiagrotech.com\/th\/csr-001\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Leela Games&quot; Annual Sports Day 2024 - CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04\" \/>\n<meta property=\"og:description\" content=\"On January 6, 2024, Chumporn Palm Oil Industry Public Company Limited, along with its subsidiaries, organized the 2024 annual sports event &quot;Leela Games&quot; to foster relationships...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cpiagrotech.com\/th\/csr-001\/\" \/>\n<meta property=\"og:site_name\" content=\"CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-06T05:31:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T15:23:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1327\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ADMIN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ADMIN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cpiagrotech.com\/csr-001\/\",\"url\":\"https:\/\/www.cpiagrotech.com\/csr-001\/\",\"name\":\"\\\"Leela Games\\\" Annual Sports Day 2024 - CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04\",\"isPartOf\":{\"@id\":\"https:\/\/www.cpiagrotech.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cpiagrotech.com\/csr-001\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cpiagrotech.com\/csr-001\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg\",\"datePublished\":\"2024-01-06T05:31:59+00:00\",\"dateModified\":\"2024-06-24T15:23:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.cpiagrotech.com\/#\/schema\/person\/ccec966e7fcb875b132b27fdf932bcaf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cpiagrotech.com\/csr-001\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cpiagrotech.com\/csr-001\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.cpiagrotech.com\/csr-001\/#primaryimage\",\"url\":\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg\",\"contentUrl\":\"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg\",\"width\":2560,\"height\":1327},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cpiagrotech.com\/csr-001\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cpiagrotech.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Leela Games&#8221; Annual Sports Day 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cpiagrotech.com\/#website\",\"url\":\"https:\/\/www.cpiagrotech.com\/\",\"name\":\"CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04\",\"description\":\"\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e38\u0e4b\u0e22\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e41\u0e25\u0e30 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cpiagrotech.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cpiagrotech.com\/#\/schema\/person\/ccec966e7fcb875b132b27fdf932bcaf\",\"name\":\"ADMIN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.cpiagrotech.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3258e9ee430b537cb7f39cfac15ea830806bdb5dd4356e86e7c9b30e9537cab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3258e9ee430b537cb7f39cfac15ea830806bdb5dd4356e86e7c9b30e9537cab?s=96&d=mm&r=g\",\"caption\":\"ADMIN\"},\"sameAs\":[\"https:\/\/www.cpiagrotech.com\"],\"url\":\"https:\/\/www.cpiagrotech.com\/th\/author\/cpiagrotech2024\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Leela Games\" Annual Sports Day 2024 - CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cpiagrotech.com\/th\/csr-001\/","og_locale":"th_TH","og_type":"article","og_title":"\"Leela Games\" Annual Sports Day 2024 - CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04","og_description":"On January 6, 2024, Chumporn Palm Oil Industry Public Company Limited, along with its subsidiaries, organized the 2024 annual sports event \"Leela Games\" to foster relationships...","og_url":"https:\/\/www.cpiagrotech.com\/th\/csr-001\/","og_site_name":"CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04","article_published_time":"2024-01-06T05:31:59+00:00","article_modified_time":"2024-06-24T15:23:27+00:00","og_image":[{"width":2560,"height":1327,"url":"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg","type":"image\/jpeg"}],"author":"ADMIN","twitter_card":"summary_large_image","twitter_misc":{"Written by":"ADMIN","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cpiagrotech.com\/csr-001\/","url":"https:\/\/www.cpiagrotech.com\/csr-001\/","name":"\"Leela Games\" Annual Sports Day 2024 - CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04","isPartOf":{"@id":"https:\/\/www.cpiagrotech.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cpiagrotech.com\/csr-001\/#primaryimage"},"image":{"@id":"https:\/\/www.cpiagrotech.com\/csr-001\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg","datePublished":"2024-01-06T05:31:59+00:00","dateModified":"2024-06-24T15:23:27+00:00","author":{"@id":"https:\/\/www.cpiagrotech.com\/#\/schema\/person\/ccec966e7fcb875b132b27fdf932bcaf"},"breadcrumb":{"@id":"https:\/\/www.cpiagrotech.com\/csr-001\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cpiagrotech.com\/csr-001\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.cpiagrotech.com\/csr-001\/#primaryimage","url":"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg","contentUrl":"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg","width":2560,"height":1327},{"@type":"BreadcrumbList","@id":"https:\/\/www.cpiagrotech.com\/csr-001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cpiagrotech.com\/"},{"@type":"ListItem","position":2,"name":"&#8220;Leela Games&#8221; Annual Sports Day 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.cpiagrotech.com\/#website","url":"https:\/\/www.cpiagrotech.com\/","name":"CPI AGROTECH - \u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04","description":"\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e38\u0e4b\u0e22\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e41\u0e25\u0e30 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e0b\u0e35\u0e1e\u0e35\u0e44\u0e2d","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cpiagrotech.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.cpiagrotech.com\/#\/schema\/person\/ccec966e7fcb875b132b27fdf932bcaf","name":"ADMIN","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.cpiagrotech.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f3258e9ee430b537cb7f39cfac15ea830806bdb5dd4356e86e7c9b30e9537cab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3258e9ee430b537cb7f39cfac15ea830806bdb5dd4356e86e7c9b30e9537cab?s=96&d=mm&r=g","caption":"ADMIN"},"sameAs":["https:\/\/www.cpiagrotech.com"],"url":"https:\/\/www.cpiagrotech.com\/th\/author\/cpiagrotech2024\/"}]}},"jetpack_featured_media_url":"https:\/\/www.cpiagrotech.com\/wp-content\/uploads\/2024\/06\/csr_19012024-165009-scaled.jpeg","_links":{"self":[{"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/posts\/7291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/comments?post=7291"}],"version-history":[{"count":10,"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/posts\/7291\/revisions"}],"predecessor-version":[{"id":7302,"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/posts\/7291\/revisions\/7302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/media\/7267"}],"wp:attachment":[{"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/media?parent=7291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/categories?post=7291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cpiagrotech.com\/th\/wp-json\/wp\/v2\/tags?post=7291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}